{"id":23,"count":2,"description":"","link":"https:\/\/boostelearning.com\/hi\/vendor\/red-hat\/","name":"Red Hat","slug":"red-hat","taxonomy":"course_vendor","meta":[],"_links":{"self":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course_vendor\/23","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course_vendor"}],"about":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/taxonomies\/course_vendor"}],"wp:post_type":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course?course_vendor=23"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}