{"id":14,"count":8,"description":"","link":"https:\/\/boostelearning.com\/hi\/vendor\/comptia\/","name":"CompTIA","slug":"comptia","taxonomy":"course_vendor","meta":[],"_links":{"self":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course_vendor\/14","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course_vendor"}],"about":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/taxonomies\/course_vendor"}],"wp:post_type":[{"href":"https:\/\/boostelearning.com\/hi\/wp-json\/wp\/v2\/course?course_vendor=14"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}