{"id":1503,"date":"2026-07-14T16:09:39","date_gmt":"2026-07-14T20:09:39","guid":{"rendered":"https:\/\/boostelearning.com\/courses\/general\/pmi-acp-agile-certified-practitioner-2\/"},"modified":"2026-07-14T16:09:39","modified_gmt":"2026-07-14T20:09:39","slug":"pmi-acp-agile-certified-practitioner","status":"publish","type":"course","link":"https:\/\/boostelearning.com\/fr\/courses\/general\/pmi-acp-agile-certified-practitioner\/","title":{"rendered":"Formation en ligne et pr\u00e9paration \u00e0 la certification PMI-ACP (Praticien Certifi\u00e9 Agile)"},"content":{"rendered":"<p>La certification Agile Certified Practitioner (PMI-ACP) du PMI est une certification de niveau praticien pour les professionnels agiles. Contrairement aux certifications li\u00e9es \u00e0 un seul cadre, le PMI-ACP valide les connaissances \u00e0 travers plusieurs m\u00e9thodologies agiles &#8211; Scrum, Kanban, Lean, Extreme Programming (XP) et les cadres \u00e0 grande \u00e9chelle comme SAFe &#8211; refl\u00e9tant la r\u00e9alit\u00e9 multi-m\u00e9thode de la livraison agile en entreprise.<\/p>\n<p>Le programme de pr\u00e9paration au PMI-ACP de Boost eLearning offre <strong>21 heures de contact de formation agile<\/strong>, r\u00e9pondant \u00e0 l&#8217;exigence obligatoire de formation du PMI pour la certification. Le programme est structur\u00e9 autour du PMI-ACP Examination Content Outline et couvre les sept domaines suivants : Principes et \u00e9tat d&#8217;esprit agiles ; Livraisons ax\u00e9es sur la valeur ; Engagement des parties prenantes ; Performance de l&#8217;\u00e9quipe ; Planification adaptative ; D\u00e9tection et r\u00e9solution des probl\u00e8mes ; et Am\u00e9lioration continue.<\/p>\n<p>Disponible en ligne en auto-formation, en virtuel en direct et sur site, toutes les formations sont anim\u00e9es par des instructeurs partenaires certifi\u00e9s d\u00e9tenant des certifications agiles actives et une exp\u00e9rience pratique de la mise en \u0153uvre dans plusieurs cadres. Le design de r\u00e9tention des comp\u00e9tences de Boost eLearning renforce la ma\u00eetrise des domaines gr\u00e2ce \u00e0 des exercices bas\u00e9s sur des situations et des sc\u00e9narios pratiques qui refl\u00e8tent le style de jugement appliqu\u00e9 des questions de l&#8217;examen PMI-ACP.<\/p>\n<p>Le PMI-ACP est valoris\u00e9 par les praticiens qui travaillent \u00e0 travers des environnements Scrum, Kanban et hybrides et qui souhaitent une certification reconnaissant l&#8217;\u00e9tendue agile plut\u00f4t que la profondeur d&#8217;un seul cadre. Il est particuli\u00e8rement pertinent pour les chefs de projet, les propri\u00e9taires de produit, les scrum masters, les coaches agiles et les leaders d&#8217;\u00e9quipe op\u00e9rant dans des organisations o\u00f9 la livraison agile et hybride est la norme.<\/p>\n<p>Le cours comprend des examens pratiques complets avec explications, une r\u00e9f\u00e9rence de comparaison inter-cadre et notre garantie de r\u00e9ussite. Les PDUs obtenus gr\u00e2ce \u00e0 ce cours comptent pour le renouvellement du PMI-ACP, soutenant le d\u00e9veloppement professionnel continu au-del\u00e0 de la certification.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00e9montrer une expertise agile inter-technologies avec le PMI-ACP\u2014la certification agile de niveau praticien de PMI couvrant Scrum, Kanban, Lean, XP et SAFe. Le programme satisfait l&#8217;exigence de formation de 21 heures de contact et vous pr\u00e9pare \u00e0 la diversit\u00e9 des m\u00e9thodologies agiles test\u00e9es \u00e0 l&#8217;examen.<\/p>\n","protected":false},"featured_media":141,"menu_order":0,"template":"","meta":{"bel_standfirst":"","bel_faq":"","bel_outcomes":"","bel_audience":"","bel_outline":"","bel_exam":"","bel_livelabs":"","bel_duration":"","bel_exam_code":"","bel_level":"","bel_price":"","bel_rating":"","bel_reviews":"","bel_instructors":"","bel_image_credit":"","bel_result_num":"","bel_result_label":"","bel_customer":"","bel_industry":"","bel_credentials":"","bel_courses_taught":"","bel_meta_desc":""},"course_cat":[],"course_vendor":[],"course_modality":[],"course_level":[],"class_list":["post-1503","course","type-course","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course\/1503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course"}],"about":[{"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/types\/course"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/media\/141"}],"wp:attachment":[{"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/media?parent=1503"}],"wp:term":[{"taxonomy":"course_cat","embeddable":true,"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course_cat?post=1503"},{"taxonomy":"course_vendor","embeddable":true,"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course_vendor?post=1503"},{"taxonomy":"course_modality","embeddable":true,"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course_modality?post=1503"},{"taxonomy":"course_level","embeddable":true,"href":"https:\/\/boostelearning.com\/fr\/wp-json\/wp\/v2\/course_level?post=1503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}