{"id":27,"count":1,"description":"","link":"https:\/\/boostelearning.com\/ar\/vendor\/peoplecert\/","name":"PeopleCert","slug":"peoplecert","taxonomy":"course_vendor","meta":[],"_links":{"self":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course_vendor\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course_vendor"}],"about":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/taxonomies\/course_vendor"}],"wp:post_type":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course?course_vendor=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}