{"id":21,"count":3,"description":"","link":"https:\/\/boostelearning.com\/ar\/vendor\/pmi\/","name":"PMI","slug":"pmi","taxonomy":"course_vendor","meta":[],"_links":{"self":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course_vendor\/21","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course_vendor"}],"about":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/taxonomies\/course_vendor"}],"wp:post_type":[{"href":"https:\/\/boostelearning.com\/ar\/wp-json\/wp\/v2\/course?course_vendor=21"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}